{"id":8560,"date":"2022-03-24T11:25:51","date_gmt":"2022-03-24T03:25:51","guid":{"rendered":"https:\/\/www.chefstemp.com\/?page_id=8560"},"modified":"2023-12-05T20:27:39","modified_gmt":"2023-12-05T12:27:39","slug":"social-media-specialist","status":"publish","type":"page","link":"https:\/\/www.chefstemp.com\/nl\/careers\/social-media-specialist\/","title":{"rendered":"Social media specialist"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><h3><span style=\"color: #ff9900;\">Social Media Specialist<\/span><\/h3>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\" style=\"--awb-text-transform:none;\"><div class=\"underlinedHeader underlinedHeaderView\">\n<h4 class=\"leftContent fusion-responsive-typography-calculated\" style=\"--fontsize: 30; line-height: 1.3;\" data-fontsize=\"30\" data-lineheight=\"39px\"><strong>Job Details<br \/>\n<\/strong><\/h4>\n<hr \/>\n<\/div>\n<div class=\" row\" aria-label=\"Job Details\">\n<div class=\" col-md-12 local-tax-col local-ee\">\n<div id=\"Job Location-row\" class=\"row formRowStandard \"><em><label class=\"standard\" for=\"\">ChefsTemp is looking for a Social Media Specialist who brings a proven ability to increase public engagement with content, ideas, and promotions through careful, consistent posts that maintain the right balance between platform relevance and brand professionalism.<\/label><\/em><\/div>\n<div class=\"row formRowStandard \">\n<p><em><label class=\"standard\" for=\"\">Job Location: USA<\/label><\/em><\/p>\n<\/div>\n<div id=\"Position Type-row\" class=\"row formRowStandard \"><em><em><label class=\"standard\" for=\"\">Position Type: <\/label><\/em><label class=\"standard\" for=\"\">R<\/label>emote position<\/em><\/div>\n<div class=\"row formRowStandard \">\n<p><em>\u00a0<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"table-2 temperature\">\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">Job Title<\/th>\n<th align=\"left\">Social Media Specialist<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">Employment Type<\/td>\n<td align=\"left\">Part-time<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Base Salary<\/td>\n<td align=\"left\">25,000 USD<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Job Benefits<\/td>\n<td align=\"left\">Huge bonuses<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Education Requirements<\/td>\n<td align=\"left\">College degree in Marketing related fields<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Experience Requirements<\/td>\n<td align=\"left\">3-5 years in a marketing team in charge of digital marketing<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Qualifications<\/td>\n<td align=\"left\">Ability to adapt to different client and customer requirements, learns new skills easily, enjoys coming up with new suggestions<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Responsibilities<\/td>\n<td align=\"left\">Grow social media visibility and engagement across all platforms with a particular focus on Instagram, Facebook, Twitter, LinkedIn, Tik Tok and Pinterest.<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Skills<\/td>\n<td align=\"left\">Create and curate daily social media content including text and graphic layout\/design in conjunction with other social media team members<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Industry<\/td>\n<td align=\"left\">Electronics and appliances industry<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Job Location<\/td>\n<td align=\"left\">Distance working, whole US<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Working Hours<\/td>\n<td align=\"left\">20 hours per week<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-3\" style=\"--awb-text-transform:none;\"><p><strong>Essential Responsibilities:<\/strong><\/p>\n<ul>\n<li>Grow social media visibility and engagement across all platforms with a particular focus on Instagram, Facebook, Twitter, LinkedIn, Tik Tok and Pinterest.<\/li>\n<li>Create and curate daily social media content including text and graphic layout\/design in conjunction with other social media team members<\/li>\n<li>Monitor, identify and help respond to public comments and questions<\/li>\n<li>Build and maintain a strong professional brand identity at all times<\/li>\n<li>Track and create summary reports of analytic data<\/li>\n<li>Keep and maintain good community relations<\/li>\n<li>Design content and paid ad content when needed<\/li>\n<li>Create engaging, fresh social media content that drives engagement and product\/brand discovery<\/li>\n<li>Collaborate with team members on marketing videos, campaigns, launches, etc<\/li>\n<li>Keep up to date on new and emerging trends, tools, platforms, and practices in social<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<p><em>To apply for the position, please upload your information in the form below:<\/em><\/p>\n<p><span style=\"color: #ff9900;\">\u00a0<\/span><\/p>\n<\/div><div class=\"fusion-widget fusion-widget-element fusion-widget-area fusion-content-widget-area wpWidget-1 wpforms_widget\" style=\"--awb-fusion-border-size:0px;--awb-fusion-border-style:solid;\"><div class=\"widget wpforms-widget\"><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-8757\"><form id=\"wpforms-form-8757\" class=\"wpforms-validate wpforms-form\" data-formid=\"8757\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/nl\/wp-json\/wp\/v2\/pages\/8560?wpforms_form_id=8757\" data-token=\"06b4fe87a3c8169c5e2b84b4b16d068d\" data-token-time=\"1778697284\"><noscript class=\"wpforms-error-noscript\">Schakel JavaScript in je browser in om dit formulier in te vullen.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-8757-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-8757-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-8757-field_0\" class=\"wpforms-field-sublabel after\">Voornaam<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-8757-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-8757-field_0-last\" class=\"wpforms-field-sublabel after\">Achternaam<\/label><\/div><\/div><\/div><div id=\"wpforms-8757-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-8757-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-8757-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-8757-field_2-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-8757-field_2\">Phone<\/label><input type=\"tel\" id=\"wpforms-8757-field_2\" class=\"wpforms-field-medium wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][2]\" aria-label=\"Phone\" ><\/div><div id=\"wpforms-8757-field_3-container\" class=\"wpforms-field wpforms-field-address\" data-field-id=\"3\"><label class=\"wpforms-field-label\">Address<\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div ><input type=\"text\" id=\"wpforms-8757-field_3\" class=\"wpforms-field-address-address1\" name=\"wpforms[fields][3][address1]\" ><label for=\"wpforms-8757-field_3\" class=\"wpforms-field-sublabel after\">Adres regel 1<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div ><input type=\"text\" id=\"wpforms-8757-field_3-address2\" class=\"wpforms-field-address-address2\" name=\"wpforms[fields][3][address2]\" ><label for=\"wpforms-8757-field_3-address2\" class=\"wpforms-field-sublabel after\">Adres regel 2<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-8757-field_3-city\" class=\"wpforms-field-address-city\" name=\"wpforms[fields][3][city]\" ><label for=\"wpforms-8757-field_3-city\" class=\"wpforms-field-sublabel after\">Stad<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><select id=\"wpforms-8757-field_3-state\" class=\"wpforms-field-address-state\" name=\"wpforms[fields][3][state]\" ><option class=\"placeholder\" value=\"\" selected disabled>--- Selecteer state ---<\/option><option value=\"AL\" >Alabama<\/option><option value=\"AK\" >Alaska<\/option><option value=\"AZ\" >Arizona<\/option><option value=\"AR\" >Arkansas<\/option><option value=\"CA\" >Californi\u00eb<\/option><option value=\"CO\" >Colorado<\/option><option value=\"CT\" >Connecticut<\/option><option value=\"DE\" >Delaware<\/option><option value=\"DC\" >District of Columbia<\/option><option value=\"FL\" >Florida<\/option><option value=\"GA\" >Georgia<\/option><option value=\"HI\" >Hawaii<\/option><option value=\"ID\" >Idaho<\/option><option value=\"IL\" >Illinois<\/option><option value=\"IN\" >Indiana<\/option><option value=\"IA\" >Iowa<\/option><option value=\"KS\" >Kansas<\/option><option value=\"KY\" >Kentucky<\/option><option value=\"LA\" >Louisiana<\/option><option value=\"ME\" >Maine<\/option><option value=\"MD\" >Maryland<\/option><option value=\"MA\" >Massachusetts<\/option><option value=\"MI\" >Michigan<\/option><option value=\"MN\" >Minnesota<\/option><option value=\"MS\" >Mississippi<\/option><option value=\"MO\" >Missouri<\/option><option value=\"MT\" >Montana<\/option><option value=\"NE\" >Nebraska<\/option><option value=\"NV\" >Nevada<\/option><option value=\"NH\" >New Hampshire<\/option><option value=\"NJ\" >New Jersey<\/option><option value=\"NM\" >New Mexico<\/option><option value=\"NY\" >New York<\/option><option value=\"NC\" >North Carolina<\/option><option value=\"ND\" >Noord-Dakota<\/option><option value=\"OH\" >Ohio<\/option><option value=\"OK\" >Oklahoma<\/option><option value=\"OR\" >Oregon<\/option><option value=\"PA\" >Pennsylvania<\/option><option value=\"RI\" >Rhode Island<\/option><option value=\"SC\" >South Carolina<\/option><option value=\"SD\" >South Dakota<\/option><option value=\"TN\" >Tennessee<\/option><option value=\"TX\" >Texas<\/option><option value=\"UT\" >Utah<\/option><option value=\"VT\" >Vermont<\/option><option value=\"VA\" >Virginia<\/option><option value=\"WA\" >Washington<\/option><option value=\"WV\" >West Virginia<\/option><option value=\"WI\" >Wisconsin<\/option><option value=\"WY\" >Wyoming<\/option><\/select><label for=\"wpforms-8757-field_3-state\" class=\"wpforms-field-sublabel after\">Provincie<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-8757-field_3-postal\" class=\"wpforms-field-address-postal wpforms-masked-input\" data-inputmask-mask=\"(99999)|(99999-9999)\" data-inputmask-keepstatic=\"true\" data-rule-inputmask-incomplete=\"1\" name=\"wpforms[fields][3][postal]\" ><label for=\"wpforms-8757-field_3-postal\" class=\"wpforms-field-sublabel after\">Postcode<\/label><\/div><\/div><\/div><div id=\"wpforms-8757-field_9-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"9\"><label class=\"wpforms-field-label\">Which position are you applying for? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-8757-field_9\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-8757-field_9_1\" name=\"wpforms[fields][9][]\" value=\"Social Media Specialist\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-8757-field_9_1\">Social Media Specialist<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-8757-field_9_2\" name=\"wpforms[fields][9][]\" value=\"Videographer \/ Photographer\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-8757-field_9_2\">Videographer \/ Photographer<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-8757-field_9_3\" name=\"wpforms[fields][9][]\" value=\"Email Marketing Specialist\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-8757-field_9_3\">Email Marketing Specialist<\/label><\/li><\/ul><\/div><div id=\"wpforms-8757-field_4-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"4\"><label class=\"wpforms-field-label\">How did you find out about this position?<\/label><ul id=\"wpforms-8757-field_4\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-8757-field_4_1\" name=\"wpforms[fields][4]\" value=\"Job platform\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-8757-field_4_1\">Job platform<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-8757-field_4_2\" name=\"wpforms[fields][4]\" value=\"Social Media (YouTube, Facebook,...)\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-8757-field_4_2\">Social Media (YouTube, Facebook,...)<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-8757-field_4_3\" name=\"wpforms[fields][4]\" value=\"Search Engine\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-8757-field_4_3\">Search Engine<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-8757-field_4_4\" name=\"wpforms[fields][4]\" value=\"Other\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-8757-field_4_4\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-8757-field_7-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-8757-field_7\">Upload your resume <span class=\"wpforms-required-label\">*<\/span><\/label><div\n\t\tclass=\"wpforms-uploader wpforms-field-required\"\n\t\tdata-field-id=\"7\"\n\t\tdata-form-id=\"8757\"\n\t\tdata-input-name=\"wpforms_8757_7\"\n\t\tdata-extensions=\"pdf,doc,docx\"\n\t\tdata-max-size=\"5242880\"\n\t\tdata-max-file-number=\"1\"\n\t\tdata-post-max-size=\"524288000\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-8757-field_7\"\n\t\tname=\"wpforms_8757_7\" required\t\tvalue=\"\">\n<\/div><div id=\"wpforms-8757-field_8-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-8757-field_8\">Additional information<\/label><textarea id=\"wpforms-8757-field_8\" class=\"wpforms-field-medium\" name=\"wpforms[fields][8]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"8757\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.chefstemp.com\/nl\/wp-json\/wp\/v2\/pages\/8560\"><input type=\"hidden\" name=\"url_referer\" value=\"\">\t\t<div id=\"cf-turnstile-wpf-4124249868\"\r\n\t\tclass=\"cf-turnstile\" \t\tdata-sitekey=\"0x4AAAAAAA6HYYG1xpRpowv3\"\r\n\t\tdata-theme=\"light\"\r\n\t\tdata-language=\"auto\"\r\n\t\tdata-size=\"normal\"\r\n\t\tdata-retry=\"auto\" data-retry-interval=\"1000\"\r\n\t\tdata-refresh-expired=\"auto\"\r\n\t\tdata-action=\"wpforms-8757\"\r\n\t\t\t\tdata-appearance=\"always\"><\/div>\r\n\t\t\t<script>document.addEventListener(\"DOMContentLoaded\", function() { setTimeout(function(){ var e=document.getElementById(\"cf-turnstile-wpf-4124249868\"); e&&!e.innerHTML.trim()&&(turnstile.remove(\"#cf-turnstile-wpf-4124249868\"), turnstile.render(\"#cf-turnstile-wpf-4124249868\", {sitekey:\"0x4AAAAAAA6HYYG1xpRpowv3\"})); }, 100); });<\/script>\r\n\t\t\t<br class=\"cf-turnstile-br cf-turnstile-br-wpf-4124249868\">\r\n\t\t\t\t<style>#cf-turnstile-wpf-4124249868 { margin-left: -15px; }<\/style>\r\n\t\t<button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-8757\" class=\"wpforms-submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":8312,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8560","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chefstemp.com\/nl\/wp-json\/wp\/v2\/pages\/8560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chefstemp.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.chefstemp.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.chefstemp.com\/nl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chefstemp.com\/nl\/wp-json\/wp\/v2\/comments?post=8560"}],"version-history":[{"count":0,"href":"https:\/\/www.chefstemp.com\/nl\/wp-json\/wp\/v2\/pages\/8560\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.chefstemp.com\/nl\/wp-json\/wp\/v2\/pages\/8312"}],"wp:attachment":[{"href":"https:\/\/www.chefstemp.com\/nl\/wp-json\/wp\/v2\/media?parent=8560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}